{"id":21299,"date":"2023-12-22T13:24:40","date_gmt":"2023-12-22T12:24:40","guid":{"rendered":"https:\/\/www.wepaflyer.com\/?post_type=product&#038;p=21299"},"modified":"2026-05-04T11:34:45","modified_gmt":"2026-05-04T09:34:45","slug":"stex-dy-heart-toom","status":"publish","type":"product","link":"https:\/\/www.wepaflyer.com\/de\/produkt\/stex-dy-heart-toom\/","title":{"rendered":"STex DY-Heart Waageleinen"},"content":{"rendered":"<h3>STEX \u201eDY-HEART\u201c WAAGELEINEN<\/h3>\n<h5>Dehnungsfreie Waageleinen mit Dyneema-Kern von STex | In 4 St\u00e4rken<\/h5>\n<p>Die Waageleinen von <b>STex<\/b> sind von ausgezeichneter Qualit\u00e4t.<\/p>\n<p>Ohne Dehnung und ideal zum Anbringen von festen Knoten und Schlaufen, es verrutscht kaum.<\/p>\n<p>F\u00fcr jeden Drachen die passende St\u00e4rke mit Farbkennzeichnungsfaden, als Meterware bestellbar!<\/p>\n<p><strong>Erh\u00e4ltlich in 5 verschiedenen St\u00e4rken:<\/strong><\/p>\n<ul>\n<li>Die 49daN (\u00d8 0,8mm) wird in <b>Schwarz mit gelbem Kennfaden<\/b>\u00a0geliefert.<\/li>\n<li>Die 72daN (\u00d8 0,9mm) wird in <strong>Schwarz mit rotem Kennfaden geliefert.<\/strong><\/li>\n<li>Die 110daN (\u00d8 1,25mm) wird in <strong>hellblau (blau) ohne Kennfaden geliefert.<\/strong><\/li>\n<li>Die 130 daN (\u00d8 1,3 mm) wird in <strong>Schwarz mit wei\u00dfem Kennfaden geliefert.<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dehnungsfreie Waageleinen mit Dyneema-Kern von STex | In 4 St\u00e4rken<\/p>\n","protected":false},"featured_media":11413,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2171,1348],"product_tag":[3636],"class_list":{"0":"post-21299","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-drachenschnure","7":"product_cat-marken","8":"product_tag-onderdelen","9":"pa_grootte-49dan-de-2","10":"pa_grootte-72dan-de-2","11":"pa_grootte-95dan-de-2","12":"pa_grootte-110dan-de-2","13":"pa_grootte-130dan-de-2","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/product\/21299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/comments?post=21299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/media\/11413"}],"wp:attachment":[{"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/media?parent=21299"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/product_brand?post=21299"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/product_cat?post=21299"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.wepaflyer.com\/de\/wp-json\/wp\/v2\/product_tag?post=21299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}